{"id":14016,"date":"2016-05-03T16:46:19","date_gmt":"2016-05-03T14:46:19","guid":{"rendered":"http:\/\/www.surfingtheplanet.com\/it\/?page_id=14016"},"modified":"2022-04-01T21:43:06","modified_gmt":"2022-04-01T19:43:06","slug":"stampa","status":"publish","type":"page","link":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/","title":{"rendered":"Stampa"},"content":{"rendered":"<p>In questa sezione abbiamo raccolto tutto quello che si dice di noi, sia in altri portali on- line come nella stampa scritta ed in radio.<\/p>\n<p><strong>INTERVISTE<\/strong><\/p>\n<ul>\n<li>Intervista per la radio spagnola Radio Nacional\u00a0(Anno 2016)<\/li>\n<li>Intervista per la radio spagnola\u00a0Radio Euskadi\u00a0(Anno 2016)<\/li>\n<li>Intervista per la radio spagnola Radio &#8230;&#8230;\u00a0(Anno 2016)<\/li>\n<li>Intervista per il portale di viaggi\u00a0<a href=\"http:\/\/mochilerostv.com\/surfing-the-planet-la-vuelta-al-mundo-17-meses\/\" target=\"_blank\" rel=\"noopener noreferrer\">&#8220;Mochileros TV&#8221;<\/a>\u00a0(Anno 2016)<\/li>\n<\/ul>\n<ul>\n<li>Intervista per il quotidiano ungherese:\u00a0<a href=\"http:\/\/www.blikk.hu\/aktualis\/hatizsakkal-jarta-be-a-vilagot-a-jegyespar\/rqkm3jd\">\u201cBlikk\u201d<\/a>\u00a0(Anno 2014)<\/li>\n<li>Intervista per il quotidiano ungherese <a href=\"https:\/\/cdn.surfingtheplanet.com\/wp-content\/uploads\/\/2014\/09\/hajdu-naplo.jpg?strip=all&w=2560\">\u201cHajd\u00fa Bihari Napl\u00f3\u201d<\/a>\u00a0(Anno 2014)<\/li>\n<li>Intervista per la radio ungherese \u201cL\u00e1nch\u00edd FM\u201d\u00a0(Anno 2014)<\/li>\n<li>Intervista sul blog di viaggi\u00a0\u00a0\u201cMytanfeet\u201d\u00a0(Anno 2014)<\/li>\n<li>Intervista sul blog di viaggi\u00a0 <a href=\"http:\/\/www.avventureviaggi.com\/viaggi\/in-viaggio-con-surfing-the-planet\/\">\u201cAvventure Viaggi\u201d<\/a>\u00a0(Anno 2014)<\/li>\n<li>Intervista per il quotidiano italiano:\u00a0<a href=\"http:\/\/mattinopadova.gelocal.it\/padova\/cronaca\/2013\/09\/17\/news\/rachele-un-viaggio-lungo-17-mesi-1.7760692\">\u201cIl Mattino di Padova\u201d<\/a>\u00a0(Anno 2013)<\/li>\n<li>Foto galleria nel sito internet del a quotidiano italiano\u00a0<a href=\"http:\/\/mattinopadova.gelocal.it\/padova\/foto-e-video\/2013\/09\/17\/fotogalleria\/i-momenti-piu-belli-del-viaggio-di-rachele-e-gabor-1.7760826#1\">&#8220;Il Mattino di Padova&#8221;<\/a>\u00a0(Anno 2013)<\/li>\n<li>Intervista per il quotidiano italiano:\u00a0<a href=\"https:\/\/www.surfingtheplanet.com\/gazettino_cortado\/\">\u201cIl Gazzettino\u201d<\/a>\u00a0(Anno 2013)<\/li>\n<li>Intervista per il quotidiano italiano:\u00a0<a href=\"https:\/\/www.surfingtheplanet.com\/articolo-piazza\/\">\u201cLa Piazza del Piovese\u201d<\/a>\u00a0(Anno 2013)<\/li>\n<li>Intervista sul il blog di viaggi\u00a0<a href=\"http:\/\/www.wetravelaroundtheworld.com\/interview-with-rachele-and-gabor-from-surfing-the-planet\/\">&#8220;We Travel around the World&#8221;<\/a>\u00a0Anno 2012)<\/li>\n<\/ul>\n<p><strong>RICONOSCIMENTI<\/strong><\/p>\n<ul>\n<li>Paco Nadal ci ha menzionato tra i 25 blogs di viaggi in lingua spagnola che raccomanda per il 2016 &#8220;<a href=\"http:\/\/blogs.elpais.com\/paco-nadal\/2016\/01\/25-blogs-viajes-recomendables.html\" target=\"_blank\" rel=\"noopener noreferrer\">25 blogs de viajes en espa\u00f1ol recomendables para el 2016\u00a0<\/a>&#8221; (Anno 2016)<\/li>\n<li>Il nostro articolo\u00a0\u201cC\u00f3mo manejar el presupuesto en un viaje. Consejos pr\u00e1cticos\u201d\u00a0\u00e8 stato selezionato come miglior articolo del mese di settembre 2013 su\u00a0<em>Hostelbookers.com\u00a0(Anno 2013)<\/em><\/li>\n<li>Il nostro <a href=\"https:\/\/www.diariodelviajero.com\/consejos\/companeros-de-ruta-solos-o-acompanados\">blog \u00e8 stato menzionato <\/a>come esempio di viaggi in coppia nella rivista digitale\u00a0<em>DiariodelViajero.com\u00a0(Anno 2013)<\/em><\/li>\n<li>Il nostro articolo\u00a0\u201d<a href=\"https:\/\/www.diariodelviajero.com\/diario-del-viajero\/companeros-de-ruta-lugares-con-historias-lugares-por-conocer\">Sentirse en casa por el mundo\u201d<\/a>\u00a0\u00e8 stato menzionato nella rivista digitale <em>DiariodelViajero.com\u00a0(Anno 2013)<\/em><\/li>\n<li>Il nostro articolo\u00a0 \u201d<a href=\"https:\/\/www.diariodelviajero.com\/diario-del-viajero\/companeros-de-ruta-solos-o-en-pareja-estos-viajeros-nos-llevan-por-el-mundo\">Padua, la ciudad del los 3 sin<\/a>\u201d\u00e8 stato menzionato nella rivista digitale <em>DiariodelViajero.com\u00a0(Anno 2013)<\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questa sezione abbiamo raccolto tutto quello che si dice di noi, sia in altri portali on- line come nella stampa scritta ed in radio. INTERVISTE Intervista per la radio spagnola Radio Nacional\u00a0(Anno 2016) Intervista per la radio spagnola\u00a0Radio Euskadi\u00a0(Anno 2016) Intervista per la radio spagnola Radio &#8230;&#8230;\u00a0(Anno 2016) Intervista per il portale di viaggi\u00a0&#8220;Mochileros [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-14016","1":"page","2":"type-page","3":"status-publish","5":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stampa - Surfing the Planet<\/title>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.surfingtheplanet.com\/it\/stampa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stampa - Surfing the Planet\" \/>\n<meta property=\"og:description\" content=\"In questa sezione abbiamo raccolto tutto quello che si dice di noi, sia in altri portali on- line come nella stampa scritta ed in radio. INTERVISTE Intervista per la radio spagnola Radio Nacional\u00a0(Anno 2016) Intervista per la radio spagnola\u00a0Radio Euskadi\u00a0(Anno 2016) Intervista per la radio spagnola Radio &#8230;&#8230;\u00a0(Anno 2016) Intervista per il portale di viaggi\u00a0&#8220;Mochileros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.surfingtheplanet.com\/it\/stampa\/\" \/>\n<meta property=\"og:site_name\" content=\"Surfing the Planet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/surfingtheplanet\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-01T19:43:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@surfingplanet\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/stampa\\\/\",\"url\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/stampa\\\/\",\"name\":\"Stampa - Surfing the Planet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#website\"},\"datePublished\":\"2016-05-03T14:46:19+00:00\",\"dateModified\":\"2022-04-01T19:43:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/stampa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/stampa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/stampa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#website\",\"url\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/\",\"name\":\"Surfing the Planet\",\"description\":\"Blog de viajes. Escapadas y grandes viajes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#organization\",\"name\":\"Surfing the Planet\",\"url\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.surfingtheplanet.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/logo_newlayout21.png?strip=all\",\"contentUrl\":\"https:\\\/\\\/cdn.surfingtheplanet.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/logo_newlayout21.png?strip=all\",\"width\":570,\"height\":110,\"caption\":\"Surfing the Planet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.surfingtheplanet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/surfingtheplanet\",\"https:\\\/\\\/x.com\\\/surfingplanet\",\"https:\\\/\\\/www.instagram.com\\\/surfingplanet\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/surfingplanet\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SurfingThePlanet\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stampa - Surfing the Planet","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/","og_locale":"it_IT","og_type":"article","og_title":"Stampa - Surfing the Planet","og_description":"In questa sezione abbiamo raccolto tutto quello che si dice di noi, sia in altri portali on- line come nella stampa scritta ed in radio. INTERVISTE Intervista per la radio spagnola Radio Nacional\u00a0(Anno 2016) Intervista per la radio spagnola\u00a0Radio Euskadi\u00a0(Anno 2016) Intervista per la radio spagnola Radio &#8230;&#8230;\u00a0(Anno 2016) Intervista per il portale di viaggi\u00a0&#8220;Mochileros [&hellip;]","og_url":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/","og_site_name":"Surfing the Planet","article_publisher":"https:\/\/www.facebook.com\/surfingtheplanet","article_modified_time":"2022-04-01T19:43:06+00:00","twitter_card":"summary_large_image","twitter_site":"@surfingplanet","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/","url":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/","name":"Stampa - Surfing the Planet","isPartOf":{"@id":"https:\/\/www.surfingtheplanet.com\/#website"},"datePublished":"2016-05-03T14:46:19+00:00","dateModified":"2022-04-01T19:43:06+00:00","breadcrumb":{"@id":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.surfingtheplanet.com\/it\/stampa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.surfingtheplanet.com\/it\/stampa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.surfingtheplanet.com\/it\/"},{"@type":"ListItem","position":2,"name":"Stampa"}]},{"@type":"WebSite","@id":"https:\/\/www.surfingtheplanet.com\/#website","url":"https:\/\/www.surfingtheplanet.com\/","name":"Surfing the Planet","description":"Blog de viajes. Escapadas y grandes viajes","publisher":{"@id":"https:\/\/www.surfingtheplanet.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.surfingtheplanet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.surfingtheplanet.com\/#organization","name":"Surfing the Planet","url":"https:\/\/www.surfingtheplanet.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.surfingtheplanet.com\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.surfingtheplanet.com\/wp-content\/uploads\/2014\/03\/logo_newlayout21.png?strip=all","contentUrl":"https:\/\/cdn.surfingtheplanet.com\/wp-content\/uploads\/2014\/03\/logo_newlayout21.png?strip=all","width":570,"height":110,"caption":"Surfing the Planet"},"image":{"@id":"https:\/\/www.surfingtheplanet.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/surfingtheplanet","https:\/\/x.com\/surfingplanet","https:\/\/www.instagram.com\/surfingplanet\/","https:\/\/www.pinterest.com\/surfingplanet","https:\/\/www.youtube.com\/user\/SurfingThePlanet"]}]}},"_links":{"self":[{"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/pages\/14016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/comments?post=14016"}],"version-history":[{"count":0,"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/pages\/14016\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.surfingtheplanet.com\/it\/wp-json\/wp\/v2\/media?parent=14016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}